{"id":2392440,"date":"2024-02-20T09:30:03","date_gmt":"2024-02-20T08:30:03","guid":{"rendered":"https:\/\/gpm.ch\/immobilien\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\/"},"modified":"2026-09-02T09:41:28","modified_gmt":"2026-09-02T07:41:28","slug":"1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa","status":"publish","type":"casawp_property","link":"https:\/\/gpm.ch\/en\/immobilien\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\/","title":{"rendered":"Uffici di varie metrature, frazionabile, in sede funzionale e prestigiosa"},"content":{"rendered":"<h2>Uffici di varie metrature in sede funzionale e prestigiosa<\/h2>\n<p>In posizione strategica nel cuore del Ticino ed in un contesto moderno ed all&#8217;avanguardia, proponiamo in locazione spazi di diversa metratura che si distinguono per la loro ampiezza e luminosit\u00e0.<\/p>\n<p>Le dimensioni generose offrono un ambiente aperto e flessibile, ideale per adattarsi alle diverse esigenze aziendali. Inoltre, questi spazi sono raffrescati \/ ventilati e dotati di pavimenti tecnici con finiture in moquette, garantendo una base solida e funzionale per la configurazione degli ambienti.<\/p>\n<p>Le aree comuni sono oggetto di particolare attenzione ed includono anche servizi di reception nonch\u00e9 un ristorante privato. La gestione mette in atto un impegno costante per mantenerle in condizioni ottimali, evidenziando una cura scrupolosa dei dettagli, visibile anche dalle numerose e curate aree verdi circostanti la propriet\u00e0.<\/p>\n<p>L&#8217;attenzione dedicata a questi spazi contribuisce a creare un ambiente accogliente, in cui l&#8217;estetica e la funzionalit\u00e0 si combinano per offrire un contesto professionale e piacevole per gli occupanti.<\/p>\n<p>Per maggiori informazioni e visite contattare il Signor Graziano Marra al nr. +41 91 973 12 70 oppure al nr. +41 79 621 03 45.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bellinzona<\/p>\n","protected":false},"author":0,"featured_media":2392441,"parent":0,"menu_order":19,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"casawp_category":[294],"casawp_feature":[245,266],"casawp_utility":[276],"casawp_location":[516,500,501],"casawp_salestype":[260],"casawp_availability":[252],"casawp_region":[268],"class_list":["post-2392440","casawp_property","type-casawp_property","status-publish","has-post-thumbnail","hentry","casawp_category-office","casawp_feature-has-elevator","casawp_feature-has-parking","casawp_utility-commercial","casawp_location-locality_bellinzona","casawp_location-country_ch","casawp_location-region_ti","casawp_salestype-rent","casawp_availability-active","casawp_region-bellinzona"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uffici di varie metrature, frazionabile, in sede funzionale e prestigiosa - GPM Global Property Management SA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gpm.ch\/en\/immobilien\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uffici di varie metrature, frazionabile, in sede funzionale e prestigiosa - GPM Global Property Management SA\" \/>\n<meta property=\"og:description\" content=\"Bellinzona\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gpm.ch\/en\/immobilien\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\/\" \/>\n<meta property=\"og:site_name\" content=\"GPM Global Property Management SA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gpmimmobiliare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T07:41:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gpm.ch\\\/en\\\/immobilien\\\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\\\/\",\"url\":\"https:\\\/\\\/gpm.ch\\\/en\\\/immobilien\\\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\\\/\",\"name\":\"Uffici di varie metrature, frazionabile, in sede funzionale e prestigiosa - GPM Global Property Management SA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gpm.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gpm.ch\\\/en\\\/immobilien\\\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gpm.ch\\\/en\\\/immobilien\\\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-12024\\\/property-1378212\\\/d98f58d74400f4085eef92b9dffdbb9a.jpeg?p=xl\",\"datePublished\":\"2024-02-20T08:30:03+00:00\",\"dateModified\":\"2026-09-02T07:41:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gpm.ch\\\/en\\\/immobilien\\\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gpm.ch\\\/en\\\/immobilien\\\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gpm.ch\\\/en\\\/immobilien\\\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-12024\\\/property-1378212\\\/d98f58d74400f4085eef92b9dffdbb9a.jpeg?p=xl\",\"contentUrl\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-12024\\\/property-1378212\\\/d98f58d74400f4085eef92b9dffdbb9a.jpeg?p=xl\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gpm.ch\\\/en\\\/immobilien\\\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/gpm.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Properties\",\"item\":\"https:\\\/\\\/gpm.ch\\\/en\\\/immobilien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Uffici di varie metrature, frazionabile, in sede funzionale e prestigiosa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gpm.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/gpm.ch\\\/en\\\/\",\"name\":\"GPM Global Property Management SA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/gpm.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gpm.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gpm.ch\\\/en\\\/#organization\",\"name\":\"GPM Global Property Management SA\",\"url\":\"https:\\\/\\\/gpm.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gpm.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gpm.ch\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2020\\\/12\\\/gpm_logo.svg\",\"contentUrl\":\"https:\\\/\\\/gpm.ch\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2020\\\/12\\\/gpm_logo.svg\",\"width\":801,\"height\":218,\"caption\":\"GPM Global Property Management SA\"},\"image\":{\"@id\":\"https:\\\/\\\/gpm.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/gpmimmobiliare\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/gpmsa\\\/\",\"https:\\\/\\\/www.instagram.com\\\/gpmimmobiliare\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uffici di varie metrature, frazionabile, in sede funzionale e prestigiosa - GPM Global Property Management SA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gpm.ch\/en\/immobilien\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\/","og_locale":"en_US","og_type":"article","og_title":"Uffici di varie metrature, frazionabile, in sede funzionale e prestigiosa - GPM Global Property Management SA","og_description":"Bellinzona","og_url":"https:\/\/gpm.ch\/en\/immobilien\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\/","og_site_name":"GPM Global Property Management SA","article_publisher":"https:\/\/www.facebook.com\/gpmimmobiliare","article_modified_time":"2026-09-02T07:41:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gpm.ch\/en\/immobilien\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\/","url":"https:\/\/gpm.ch\/en\/immobilien\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\/","name":"Uffici di varie metrature, frazionabile, in sede funzionale e prestigiosa - GPM Global Property Management SA","isPartOf":{"@id":"https:\/\/gpm.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gpm.ch\/en\/immobilien\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\/#primaryimage"},"image":{"@id":"https:\/\/gpm.ch\/en\/immobilien\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.casasoft.com\/media\/provider-12024\/property-1378212\/d98f58d74400f4085eef92b9dffdbb9a.jpeg?p=xl","datePublished":"2024-02-20T08:30:03+00:00","dateModified":"2026-09-02T07:41:28+00:00","breadcrumb":{"@id":"https:\/\/gpm.ch\/en\/immobilien\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gpm.ch\/en\/immobilien\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gpm.ch\/en\/immobilien\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\/#primaryimage","url":"https:\/\/cdn.casasoft.com\/media\/provider-12024\/property-1378212\/d98f58d74400f4085eef92b9dffdbb9a.jpeg?p=xl","contentUrl":"https:\/\/cdn.casasoft.com\/media\/provider-12024\/property-1378212\/d98f58d74400f4085eef92b9dffdbb9a.jpeg?p=xl"},{"@type":"BreadcrumbList","@id":"https:\/\/gpm.ch\/en\/immobilien\/1378216en-uffici-di-varie-metrature-frazionabile-in-sede-funzionale-e-prestigiosa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/gpm.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Properties","item":"https:\/\/gpm.ch\/en\/immobilien\/"},{"@type":"ListItem","position":3,"name":"Uffici di varie metrature, frazionabile, in sede funzionale e prestigiosa"}]},{"@type":"WebSite","@id":"https:\/\/gpm.ch\/en\/#website","url":"https:\/\/gpm.ch\/en\/","name":"GPM Global Property Management SA","description":"","publisher":{"@id":"https:\/\/gpm.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gpm.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/gpm.ch\/en\/#organization","name":"GPM Global Property Management SA","url":"https:\/\/gpm.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gpm.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/gpm.ch\/wp-content\/uploads\/sites\/14\/2020\/12\/gpm_logo.svg","contentUrl":"https:\/\/gpm.ch\/wp-content\/uploads\/sites\/14\/2020\/12\/gpm_logo.svg","width":801,"height":218,"caption":"GPM Global Property Management SA"},"image":{"@id":"https:\/\/gpm.ch\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gpmimmobiliare","https:\/\/www.linkedin.com\/company\/gpmsa\/","https:\/\/www.instagram.com\/gpmimmobiliare\/"]}]}},"_links":{"self":[{"href":"https:\/\/gpm.ch\/en\/wp-json\/wp\/v2\/casawp_property\/2392440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpm.ch\/en\/wp-json\/wp\/v2\/casawp_property"}],"about":[{"href":"https:\/\/gpm.ch\/en\/wp-json\/wp\/v2\/types\/casawp_property"}],"replies":[{"embeddable":true,"href":"https:\/\/gpm.ch\/en\/wp-json\/wp\/v2\/comments?post=2392440"}],"version-history":[{"count":1,"href":"https:\/\/gpm.ch\/en\/wp-json\/wp\/v2\/casawp_property\/2392440\/revisions"}],"predecessor-version":[{"id":2439228,"href":"https:\/\/gpm.ch\/en\/wp-json\/wp\/v2\/casawp_property\/2392440\/revisions\/2439228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpm.ch\/en\/wp-json\/wp\/v2\/media\/2392441"}],"wp:attachment":[{"href":"https:\/\/gpm.ch\/en\/wp-json\/wp\/v2\/media?parent=2392440"}],"wp:term":[{"taxonomy":"casawp_category","embeddable":true,"href":"https:\/\/gpm.ch\/en\/wp-json\/wp\/v2\/casawp_category?post=2392440"},{"taxonomy":"casawp_feature","embeddable":true,"href":"https:\/\/gpm.ch\/en\/wp-json\/wp\/v2\/casawp_feature?post=2392440"},{"taxonomy":"casawp_utility","embeddable":true,"href":"https:\/\/gpm.ch\/en\/wp-json\/wp\/v2\/casawp_utility?post=2392440"},{"taxonomy":"casawp_location","embeddable":true,"href":"https:\/\/gpm.ch\/en\/wp-json\/wp\/v2\/casawp_location?post=2392440"},{"taxonomy":"casawp_salestype","embeddable":true,"href":"https:\/\/gpm.ch\/en\/wp-json\/wp\/v2\/casawp_salestype?post=2392440"},{"taxonomy":"casawp_availability","embeddable":true,"href":"https:\/\/gpm.ch\/en\/wp-json\/wp\/v2\/casawp_availability?post=2392440"},{"taxonomy":"casawp_region","embeddable":true,"href":"https:\/\/gpm.ch\/en\/wp-json\/wp\/v2\/casawp_region?post=2392440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}